{"id":56,"count":26,"description":"","link":"https:\/\/mineralienhandel-ebeling.de\/en\/product-category\/turmalin\/","name":"Turmalin","slug":"turmalin","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Turmalin Archive - Mineralienhandel Ebeling<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mineralienhandel-ebeling.de\/en\/product-category\/turmalin\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Turmalin Archive - Mineralienhandel Ebeling\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mineralienhandel-ebeling.de\/en\/product-category\/turmalin\/\" \/>\n<meta property=\"og:site_name\" content=\"Mineralienhandel Ebeling\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mineralienhandel-ebeling.de\/wp-content\/uploads\/2024\/06\/Logo-Andreas-Ebeling.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/produkt-kategorie\\\/turmalin\\\/\",\"url\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/produkt-kategorie\\\/turmalin\\\/\",\"name\":\"Turmalin Archive - Mineralienhandel Ebeling\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/produkt-kategorie\\\/turmalin\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/produkt-kategorie\\\/turmalin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Turmalin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/#website\",\"url\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/\",\"name\":\"Mineralienhandel Ebeling\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/#organization\",\"name\":\"Mineralienhandel Ebeling\",\"url\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Logo-Andreas-Ebeling.jpg\",\"contentUrl\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Logo-Andreas-Ebeling.jpg\",\"width\":800,\"height\":800,\"caption\":\"Mineralienhandel Ebeling\"},\"image\":{\"@id\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/share\\\/1Ck1G3NdMX\\\/?mibextid=wwXIfr\",\"https:\\\/\\\/www.instagram.com\\\/mineralienhandel_ebeling?igsh=MTJ5end6dHkxMXE4NQ==&utm_source=qr\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Turmalin Archive - Mineralienhandel Ebeling","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mineralienhandel-ebeling.de\/en\/product-category\/turmalin\/","og_locale":"en_US","og_type":"article","og_title":"Turmalin Archive - Mineralienhandel Ebeling","og_url":"https:\/\/mineralienhandel-ebeling.de\/en\/product-category\/turmalin\/","og_site_name":"Mineralienhandel Ebeling","og_image":[{"width":800,"height":800,"url":"https:\/\/mineralienhandel-ebeling.de\/wp-content\/uploads\/2024\/06\/Logo-Andreas-Ebeling.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/mineralienhandel-ebeling.de\/produkt-kategorie\/turmalin\/","url":"https:\/\/mineralienhandel-ebeling.de\/produkt-kategorie\/turmalin\/","name":"Turmalin Archive - Mineralienhandel Ebeling","isPartOf":{"@id":"https:\/\/mineralienhandel-ebeling.de\/#website"},"breadcrumb":{"@id":"https:\/\/mineralienhandel-ebeling.de\/produkt-kategorie\/turmalin\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/mineralienhandel-ebeling.de\/produkt-kategorie\/turmalin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/mineralienhandel-ebeling.de\/"},{"@type":"ListItem","position":2,"name":"Turmalin"}]},{"@type":"WebSite","@id":"https:\/\/mineralienhandel-ebeling.de\/#website","url":"https:\/\/mineralienhandel-ebeling.de\/","name":"Mineralienhandel Ebeling","description":"","publisher":{"@id":"https:\/\/mineralienhandel-ebeling.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mineralienhandel-ebeling.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mineralienhandel-ebeling.de\/#organization","name":"Mineralienhandel Ebeling","url":"https:\/\/mineralienhandel-ebeling.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mineralienhandel-ebeling.de\/#\/schema\/logo\/image\/","url":"https:\/\/mineralienhandel-ebeling.de\/wp-content\/uploads\/2024\/06\/Logo-Andreas-Ebeling.jpg","contentUrl":"https:\/\/mineralienhandel-ebeling.de\/wp-content\/uploads\/2024\/06\/Logo-Andreas-Ebeling.jpg","width":800,"height":800,"caption":"Mineralienhandel Ebeling"},"image":{"@id":"https:\/\/mineralienhandel-ebeling.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/share\/1Ck1G3NdMX\/?mibextid=wwXIfr","https:\/\/www.instagram.com\/mineralienhandel_ebeling?igsh=MTJ5end6dHkxMXE4NQ==&utm_source=qr"]}]}},"_links":{"self":[{"href":"https:\/\/mineralienhandel-ebeling.de\/en\/wp-json\/wp\/v2\/product_cat\/56","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mineralienhandel-ebeling.de\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/mineralienhandel-ebeling.de\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/mineralienhandel-ebeling.de\/en\/wp-json\/wp\/v2\/product?product_cat=56"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}