{"id":1210,"date":"2024-09-21T16:05:49","date_gmt":"2024-09-21T14:05:49","guid":{"rendered":"https:\/\/mineralienhandel-ebeling.de\/?post_type=product&#038;p=1210"},"modified":"2025-10-02T21:32:25","modified_gmt":"2025-10-02T19:32:25","slug":"fluorit-xx-muscovit","status":"publish","type":"product","link":"https:\/\/mineralienhandel-ebeling.de\/en\/product\/fluorit-xx-muscovit\/","title":{"rendered":"Fluorit XX Muscovit"},"content":{"rendered":"<p>Ma\u00dfe: 8 x 5 x 8 cm<\/p>","protected":false},"excerpt":{"rendered":"<p>Ma\u00dfe: 8 x 5 x 8 cm<\/p>","protected":false},"featured_media":2612,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[58,69],"product_tag":[102],"class_list":{"0":"post-1210","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-fluorit","7":"product_cat-muscovit","8":"product_tag-namibia","10":"first","11":"outofstock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fluorit XX Muscovit - Mineralienhandel Ebeling<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mineralienhandel-ebeling.de\/en\/product\/fluorit-xx-muscovit\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fluorit XX Muscovit - Mineralienhandel Ebeling\" \/>\n<meta property=\"og:description\" content=\"Ma\u00dfe: 8 x 5 x 8 cm\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mineralienhandel-ebeling.de\/en\/product\/fluorit-xx-muscovit\/\" \/>\n<meta property=\"og:site_name\" content=\"Mineralienhandel Ebeling\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/share\/1Ck1G3NdMX\/?mibextid=wwXIfr\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-02T19:32:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mineralienhandel-ebeling.de\/wp-content\/uploads\/2024\/09\/0010-Fluorit-XX-Muscovit-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"940\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/produkt\\\/fluorit-xx-muscovit\\\/\",\"url\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/produkt\\\/fluorit-xx-muscovit\\\/\",\"name\":\"Fluorit XX Muscovit - Mineralienhandel Ebeling\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/produkt\\\/fluorit-xx-muscovit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/produkt\\\/fluorit-xx-muscovit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/0010-Fluorit-XX-Muscovit-1.webp\",\"datePublished\":\"2024-09-21T14:05:49+00:00\",\"dateModified\":\"2025-10-02T19:32:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/produkt\\\/fluorit-xx-muscovit\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/produkt\\\/fluorit-xx-muscovit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/produkt\\\/fluorit-xx-muscovit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/0010-Fluorit-XX-Muscovit-1.webp\",\"contentUrl\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/0010-Fluorit-XX-Muscovit-1.webp\",\"width\":1200,\"height\":940},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/produkt\\\/fluorit-xx-muscovit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produkte\",\"item\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fluorit XX Muscovit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/#website\",\"url\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/\",\"name\":\"Mineralienhandel Ebeling\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/#organization\",\"name\":\"Mineralienhandel Ebeling\",\"url\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Logo-Andreas-Ebeling.jpg\",\"contentUrl\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Logo-Andreas-Ebeling.jpg\",\"width\":800,\"height\":800,\"caption\":\"Mineralienhandel Ebeling\"},\"image\":{\"@id\":\"https:\\\/\\\/mineralienhandel-ebeling.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/share\\\/1Ck1G3NdMX\\\/?mibextid=wwXIfr\",\"https:\\\/\\\/www.instagram.com\\\/mineralienhandel_ebeling?igsh=MTJ5end6dHkxMXE4NQ==&utm_source=qr\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fluorit XX Muscovit - Mineralienhandel Ebeling","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mineralienhandel-ebeling.de\/en\/product\/fluorit-xx-muscovit\/","og_locale":"en_US","og_type":"article","og_title":"Fluorit XX Muscovit - Mineralienhandel Ebeling","og_description":"Ma\u00dfe: 8 x 5 x 8 cm","og_url":"https:\/\/mineralienhandel-ebeling.de\/en\/product\/fluorit-xx-muscovit\/","og_site_name":"Mineralienhandel Ebeling","article_publisher":"https:\/\/www.facebook.com\/share\/1Ck1G3NdMX\/?mibextid=wwXIfr","article_modified_time":"2025-10-02T19:32:25+00:00","og_image":[{"width":1200,"height":940,"url":"https:\/\/mineralienhandel-ebeling.de\/wp-content\/uploads\/2024\/09\/0010-Fluorit-XX-Muscovit-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mineralienhandel-ebeling.de\/produkt\/fluorit-xx-muscovit\/","url":"https:\/\/mineralienhandel-ebeling.de\/produkt\/fluorit-xx-muscovit\/","name":"Fluorit XX Muscovit - Mineralienhandel Ebeling","isPartOf":{"@id":"https:\/\/mineralienhandel-ebeling.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mineralienhandel-ebeling.de\/produkt\/fluorit-xx-muscovit\/#primaryimage"},"image":{"@id":"https:\/\/mineralienhandel-ebeling.de\/produkt\/fluorit-xx-muscovit\/#primaryimage"},"thumbnailUrl":"https:\/\/mineralienhandel-ebeling.de\/wp-content\/uploads\/2024\/09\/0010-Fluorit-XX-Muscovit-1.webp","datePublished":"2024-09-21T14:05:49+00:00","dateModified":"2025-10-02T19:32:25+00:00","breadcrumb":{"@id":"https:\/\/mineralienhandel-ebeling.de\/produkt\/fluorit-xx-muscovit\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mineralienhandel-ebeling.de\/produkt\/fluorit-xx-muscovit\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mineralienhandel-ebeling.de\/produkt\/fluorit-xx-muscovit\/#primaryimage","url":"https:\/\/mineralienhandel-ebeling.de\/wp-content\/uploads\/2024\/09\/0010-Fluorit-XX-Muscovit-1.webp","contentUrl":"https:\/\/mineralienhandel-ebeling.de\/wp-content\/uploads\/2024\/09\/0010-Fluorit-XX-Muscovit-1.webp","width":1200,"height":940},{"@type":"BreadcrumbList","@id":"https:\/\/mineralienhandel-ebeling.de\/produkt\/fluorit-xx-muscovit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/mineralienhandel-ebeling.de\/"},{"@type":"ListItem","position":2,"name":"Produkte","item":"https:\/\/mineralienhandel-ebeling.de\/shop\/"},{"@type":"ListItem","position":3,"name":"Fluorit XX Muscovit"}]},{"@type":"WebSite","@id":"https:\/\/mineralienhandel-ebeling.de\/#website","url":"https:\/\/mineralienhandel-ebeling.de\/","name":"Mineralienhandel Ebeling","description":"","publisher":{"@id":"https:\/\/mineralienhandel-ebeling.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mineralienhandel-ebeling.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mineralienhandel-ebeling.de\/#organization","name":"Mineralienhandel Ebeling","url":"https:\/\/mineralienhandel-ebeling.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mineralienhandel-ebeling.de\/#\/schema\/logo\/image\/","url":"https:\/\/mineralienhandel-ebeling.de\/wp-content\/uploads\/2024\/06\/Logo-Andreas-Ebeling.jpg","contentUrl":"https:\/\/mineralienhandel-ebeling.de\/wp-content\/uploads\/2024\/06\/Logo-Andreas-Ebeling.jpg","width":800,"height":800,"caption":"Mineralienhandel Ebeling"},"image":{"@id":"https:\/\/mineralienhandel-ebeling.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/share\/1Ck1G3NdMX\/?mibextid=wwXIfr","https:\/\/www.instagram.com\/mineralienhandel_ebeling?igsh=MTJ5end6dHkxMXE4NQ==&utm_source=qr"]}]}},"_links":{"self":[{"href":"https:\/\/mineralienhandel-ebeling.de\/en\/wp-json\/wp\/v2\/product\/1210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mineralienhandel-ebeling.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mineralienhandel-ebeling.de\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mineralienhandel-ebeling.de\/en\/wp-json\/wp\/v2\/media\/2612"}],"wp:attachment":[{"href":"https:\/\/mineralienhandel-ebeling.de\/en\/wp-json\/wp\/v2\/media?parent=1210"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mineralienhandel-ebeling.de\/en\/wp-json\/wp\/v2\/product_brand?post=1210"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mineralienhandel-ebeling.de\/en\/wp-json\/wp\/v2\/product_cat?post=1210"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mineralienhandel-ebeling.de\/en\/wp-json\/wp\/v2\/product_tag?post=1210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}